{"id":3611,"date":"2024-07-23T13:25:33","date_gmt":"2024-07-23T13:25:33","guid":{"rendered":"https:\/\/stdev.xypex.com\/egypt\/?post_type=projects&#038;p=3611"},"modified":"2024-07-23T13:37:20","modified_gmt":"2024-07-23T13:37:20","slug":"complexe-valore-smouha","status":"publish","type":"projects","link":"https:\/\/xypex.com.eg\/fr\/projects\/complexe-valore-smouha\/","title":{"rendered":"Complexe Valore Smouha"},"content":{"rendered":"<p>Le complexe Valore Smouha, r\u00e9alis\u00e9 par Elghonimy for trading and contracting, a n\u00e9cessit\u00e9 des efforts consid\u00e9rables pour l\u2019imperm\u00e9abilisation en raison de d\u00e9fis majeurs li\u00e9s \u00e0 la pression hydraulique et \u00e0 la remont\u00e9e des eaux. Beton, sp\u00e9cialis\u00e9 en conseil et en produits chimiques de construction, a sp\u00e9cifi\u00e9 les solutions d&rsquo;\u00e9tanch\u00e9it\u00e9, tandis qu&rsquo;ALBatanony, responsable de l&rsquo;ing\u00e9nierie et de la gestion de projet, a supervis\u00e9 l\u2019imperm\u00e9abilisation et le b\u00e9tonnage. Le Xypex Admix C-1000 NF a \u00e9t\u00e9 un composant cl\u00e9 de ce projet, avec une utilisation d&rsquo;environ 35 tonnes. Cet adjuvant a \u00e9t\u00e9 incorpor\u00e9 dans le b\u00e9ton des 25 cm sup\u00e9rieurs de la dalle de 100 cm et dans les murs de sout\u00e8nement de 30 cm. Il a renforc\u00e9 la r\u00e9sistance \u00e0 l&rsquo;eau gr\u00e2ce \u00e0 sa technologie de croissance cristalline, qui r\u00e9agit avec l&rsquo;eau pour obstruer les voies d&rsquo;infiltration. L&rsquo;adjuvant Xypex assure non seulement une imperm\u00e9abilit\u00e9 \u00e0 long terme, mais il am\u00e9liore \u00e9galement la durabilit\u00e9 et les capacit\u00e9s d&rsquo;autor\u00e9paration du b\u00e9ton tout en r\u00e9sistant \u00e0 une pression hydrostatique \u00e9lev\u00e9e.<\/p>\n<p>Le Xypex concentr\u00e9 a jou\u00e9 un r\u00f4le crucial dans la r\u00e9paration des fissures et des joints de la structure, combin\u00e9 avec Xypex Patch&rsquo;n Plug, un ciment hydraulique \u00e0 prise rapide, pour traiter les fuites et les d\u00e9fauts imm\u00e9diats du b\u00e9ton. Cette combinaison a assur\u00e9 une r\u00e9paration solide et durable, scellant efficacement les fissures et stoppant les infiltrations d&rsquo;eau actives. De plus, des traitements de la t\u00eate de pieu ont \u00e9t\u00e9 r\u00e9alis\u00e9s avec Xypex concentr\u00e9 pour garantir une imperm\u00e9abilisation compl\u00e8te de toute la structure. Dans l&rsquo;ensemble, l&rsquo;utilisation des produits Xypex dans le complexe Valore Smouha a permis d&rsquo;atteindre des performances sup\u00e9rieures en mati\u00e8re d&rsquo;imperm\u00e9abilisation, augmentant la durabilit\u00e9 et assurant une int\u00e9grit\u00e9 structurelle \u00e0 long terme. Cela en fait un choix fiable pour r\u00e9sister \u00e0 des pressions d&rsquo;eau \u00e9lev\u00e9es et aux d\u00e9fis pos\u00e9s par les conditions de remont\u00e9e des eaux.<\/p>\n","protected":false},"featured_media":3610,"template":"","sector":[78],"location":[69,68],"class_list":["post-3611","projects","type-projects","status-publish","has-post-thumbnail","hentry","sector-general-foundation-fr","location-alexandria-fr","location-egypt-fr"],"_links":{"self":[{"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/projects\/3611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/types\/projects"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/media\/3610"}],"wp:attachment":[{"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/media?parent=3611"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/sector?post=3611"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/xypex.com.eg\/fr\/wp-json\/wp\/v2\/location?post=3611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}